{"id":358,"date":"2023-09-20T18:05:54","date_gmt":"2023-09-20T16:05:54","guid":{"rendered":"https:\/\/travaux.obat.fr\/guides\/?p=358"},"modified":"2024-10-29T16:10:36","modified_gmt":"2024-10-29T15:10:36","slug":"machine-a-laver-fuit","status":"publish","type":"post","link":"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/","title":{"rendered":"Que faire en cas de fuite de machine \u00e0 laver ?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Votre machine \u00e0 laver fuit\u2009<\/strong>? Constater que votre salle de bain ou votre buanderie devient une pataugeoire n\u2019est pas vraiment bon signe. Si votre lave-linge baigne dans une flaque d\u2019eau, il y a peu de doute possible\u2009! Il s\u2019agit tr\u00e8s certainement d\u2019une fuite. Pour \u00e9viter d\u2019endommager votre \u00e9quipement, le sol et les meubles autour, mieux vaut faire vite. Comment r\u00e9agir\u2009? D\u00e9couvrez les solutions pour vous aider \u00e0 comprendre et localiser<strong> la fuite de votre machine \u00e0 laver<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Machine \u00e0 laver qui fuit : les causes courantes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Avant toute chose, il est primordial de <strong>localiser la source de la fuite <\/strong>au plus vite. En effet, selon la provenance de l\u2019eau, par le bas, l\u2019avant ou l\u2019arri\u00e8re, les causes peuvent \u00eatre multiples :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>un joint ab\u00eem\u00e9\u2009;<\/li>\n\n\n\n<li>une perte d\u2019\u00e9tanch\u00e9it\u00e9 de tuyaux\u2009;<\/li>\n\n\n\n<li>une \u00e9vacuation fissur\u00e9e, bouch\u00e9e ou perc\u00e9e\u2009;<\/li>\n\n\n\n<li>une pi\u00e8ce endommag\u00e9e\u2009;<\/li>\n\n\n\n<li>une pompe de vidange d\u00e9fectueuse\u2009;<\/li>\n\n\n\n<li>une durite trou\u00e9e\u2009;<\/li>\n\n\n\n<li>un simple probl\u00e8me de surcharge<\/li>\n\n\n\n<li>etc.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A lire \u00e9galement : <a href=\"https:\/\/travaux.obat.fr\/guides\/detecter-fuite-d-eau\/\" target=\"_blank\" rel=\"noreferrer noopener\">Recherche de fuite d\u2019eau : causes possibles et solutions<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Votre lave-linge fuit \u00e0 l\u2019arri\u00e8re<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si votre machine \u00e0 laver fuit par l\u2019arri\u00e8re, cela peut \u00eatre d\u00fb \u00e0 un <strong>joint d\u00e9fectueux.<\/strong> En effet, il n\u2019est pas rare de constater une perte d\u2019\u00e9tanch\u00e9it\u00e9 des tuyaux externes. Avec le temps et l\u2019usure, les tuyaux se dilatent, deviennent poreux et ne sont plus \u00e9tanches. Les joints et rondelles s\u2019ab\u00eement et peuvent laisser passer l\u2019eau. Dans ces situations, un simple remplacement de ces \u00e9l\u00e9ments suffit \u00e0 r\u00e9soudre le probl\u00e8me de fuite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, la fuite peut \u00e9galement provenir du <strong>siphon d\u2019\u00e9vacuation des eaux us\u00e9es<\/strong>. Pour vous en assurer, vous pouvez verser de l\u2019eau dans le tuyau d\u2019\u00e9vacuation, une fois votre machine \u00e0 laver \u00e9teinte. Si l\u2019eau d\u00e9borde rapidement, c\u2019est qu\u2019il y a un bouchon\u2009! Pas de panique, vous pouvez retirer celui-ci facilement \u00e0 l\u2019aide d\u2019un furet ou d\u2019un produit pour d\u00e9boucher. \u00c0 d\u00e9faut, n\u2019h\u00e9sitez pas \u00e0 faire intervenir un professionnel de la plomberie.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sachez que la fuite peut \u00e9galement \u00eatre caus\u00e9e par une <strong>d\u00e9t\u00e9rioration du palier ou du roulement<\/strong>. En effet, le joint d\u2019\u00e9tanch\u00e9it\u00e9 peut s\u2019alt\u00e9rer au fil du temps et provoquer une fuite. Cela peut aussi survenir si des r\u00e9sidus se sont coinc\u00e9s dans le roulement. Si lors d\u2019un cycle de lavage, vous constatez un bruit anormal accompagn\u00e9 notamment de traces de rouille sur le sol, c\u2019est souvent le signe que le roulement doit \u00eatre chang\u00e9\u2009!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lire \u00e9galement : <em><a rel=\"noreferrer noopener\" href=\"https:\/\/travaux.obat.fr\/guides\/plus-d-eau-chaude\/\" target=\"_blank\">Je n\u2019ai plus d\u2019eau chaude, que faire ? Causes et solutions<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Une fuite de la machine \u00e0 laver par le bas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En g\u00e9n\u00e9ral, en pr\u00e9sence d\u2019un \u00e9coulement d\u2019eau au bas de votre machine \u00e0 laver, il faut regarder du c\u00f4t\u00e9 des<strong> tuyaux internes<\/strong>. Ces derniers, aussi appel\u00e9s durites, s\u2019usent, se dilatent et se fissurent \u00e0 l\u2019usage (avec le calcaire et les produits de lavage). Le probl\u00e8me peut aussi venir d\u2019un bouchon qui se serait form\u00e9 dans une des durites ou de la perte d\u2019\u00e9tanch\u00e9it\u00e9 d\u2019un joint. Pour contr\u00f4ler que tout est en bon \u00e9tat, vous pouvez retirer la trappe et v\u00e9rifier chacune des durites.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autre responsable d\u2019une<strong> <\/strong>machine \u00e0 laver qui fuit par le bas \u00e0 l\u2019essorage :<strong> la pompe de vidange. <\/strong>Cette derni\u00e8re sert \u00e0 \u00e9vacuer l\u2019eau. Si celle-ci fuit, il sera facile de le voir. Il est aussi possible que le tuyau de vidange soit obstru\u00e9 par des impuret\u00e9s. Dans ce cas, l\u2019eau ne peut s\u2019\u00e9vacuer normalement et remonte jusqu\u2019\u00e0 d\u00e9border. Si c\u2019est bien un probl\u00e8me de vidange, la fuite n\u2019intervient alors qu\u2019\u00e0 ce moment du cycle (essorage).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, autre source possible d\u2019une fuite de lave-linge par le bas : la <strong>d\u00e9t\u00e9rioration de la cuve ou tambour<\/strong>\u2009! Cela peut vite arriver si des objets comme des pi\u00e8ces restent dans vos poches au cours du lavage. Si la cuve est cass\u00e9e ou perc\u00e9e, il sera alors n\u00e9cessaire de la remplacer.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Votre machine \u00e0 laver fuit par l\u2019avant<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Une <strong>fuite d\u2019eau par l\u2019avant de votre lave-linge<\/strong>\u2009? Le probl\u00e8me peut \u00eatre simplement li\u00e9 \u00e0 un exc\u00e8s de lessive ou \u00e0 un trop plein de linge par rapport au poids pr\u00e9vu par votre appareil. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un \u00e9coulement par l\u2019avant peut \u00e9galement se produire si la machine n\u2019est pas cal\u00e9e, et que le poids du linge se r\u00e9partit mal durant le cycle de lavage et d\u2019essorage. Il est aussi courant que cette fuite soit caus\u00e9e par un tiroir \u00e0 lessive sale ou entartr\u00e9e ou encore <strong>un joint de hublot de porte d\u00e9fectueux<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autre explication d\u2019un \u00e9coulement par l\u2019avant : une <strong>d\u00e9faillance du pressostat ou de la chambre de compression<\/strong>. Ces \u00e9l\u00e9ments permettent de r\u00e9guler le niveau d\u2019eau dans la cuve. Si le nettoyage de ces pi\u00e8ces ne suffit pas \u00e0 r\u00e9gler le probl\u00e8me, il faudra alors proc\u00e9der \u00e0 leur remplacement.<\/p>\n\n\n    <div class=\"bon-a-savoir\">\r\n        <div class=\"bon-a-savoir-wrapper\">\r\n            <div class=\"bon-a-savoir-header\">\r\n                <div class=\"bon-a-savoir-header-icon\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\">\r\n                        <path d=\"M0 16C0 7.16344 7.16344 0 16 0C24.8366 0 32 7.16344 32 16V32H16C7.16344 32 0 24.8366 0 16Z\" fill=\"#1591F0\" \/>\r\n                        <path d=\"M13.3359 15.3966C13.3359 14.9167 13.5266 14.4564 13.8659 14.1171C14.2053 13.7777 14.6655 13.5871 15.1455 13.5871H17.5582C18.0381 13.5871 18.4983 13.7777 18.8377 14.1171C19.177 14.4564 19.3677 14.9167 19.3677 15.3966V22.0315H19.9709C20.4508 22.0315 20.911 22.2222 21.2504 22.5615C21.5897 22.9009 21.7804 23.3611 21.7804 23.8411C21.7804 24.321 21.5897 24.7812 21.2504 25.1206C20.911 25.4599 20.4508 25.6506 19.9709 25.6506H15.1455C14.6655 25.6506 14.2053 25.4599 13.8659 25.1206C13.5266 24.7812 13.3359 24.321 13.3359 23.8411C13.3359 23.3611 13.5266 22.9009 13.8659 22.5615C14.2053 22.2222 14.6655 22.0315 15.1455 22.0315H15.7486V17.2061H15.1455C14.6655 17.2061 14.2053 17.0155 13.8659 16.6761C13.5266 16.3368 13.3359 15.8765 13.3359 15.3966ZM16.955 11.1744C16.3151 11.1744 15.7014 10.9202 15.249 10.4677C14.7965 10.0153 14.5423 9.40158 14.5423 8.7617C14.5423 8.12181 14.7965 7.50813 15.249 7.05566C15.7014 6.60319 16.3151 6.349 16.955 6.349C17.5949 6.349 18.2086 6.60319 18.661 7.05566C19.1135 7.50813 19.3677 8.12181 19.3677 8.7617C19.3677 9.40158 19.1135 10.0153 18.661 10.4677C18.2086 10.9202 17.5949 11.1744 16.955 11.1744Z\" fill=\"white\" \/>\r\n                    <\/svg>\r\n                <\/div>\r\n                <div class=\"bon-a-savoir-header-title\">Bon \u00e0 savoir<\/div>\r\n            <\/div>\r\n\r\n            <div class=\"bon-a-savoir-content\">\r\n                <p>Le module de votre lave-linge est g\u00e9r\u00e9 par une carte \u00e9lectronique. Si celle-ci est d\u00e9fectueuse, elle peut alimenter par erreur le moteur et l\u2019\u00e9lectrovanne et provoquer une fuite.<\/p>\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\n\n\n<p class=\"wp-block-paragraph\"><em>A lire \u00e9galement : <a href=\"https:\/\/travaux.obat.fr\/guides\/deboucher-lavabo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Comment d\u00e9boucher un lavabo\u2009? 7 astuces qui marchent<\/a><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Que faire en cas de fuite de machine \u00e0 laver ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pour <strong>r\u00e9parer une machine \u00e0 laver qui fuit<\/strong>, certaines pr\u00e9cautions doivent \u00eatre prises. La premi\u00e8re chose \u00e0 faire est de mettre l\u2019appareil hors tension et de veiller \u00e0 ce que les fils \u00e9lectriques ne baignent pas dans l\u2019eau. Si ce geste peut \u00eatre logique, il est tout de m\u00eame important de le rappeler\u2009! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une fois votre machine d\u00e9branch\u00e9e, pensez \u00e9galement \u00e0 prendre le temps d\u2019\u00e9ponger l\u2019eau qui se trouve sur le sol. Par la suite, vous pourrez inspecter les diff\u00e9rents \u00e9l\u00e9ments qui pourraient \u00eatre<strong> responsables de la fuite<\/strong>. \u00c0 chaque cause, une solution\u2009!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour vous guider, voici <strong>comment r\u00e9parer un lave-linge qui fuit en <\/strong>fonction de l\u2019\u00e9l\u00e9ment endommag\u00e9 :<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Arri\u00e8re de la machine \u00e0 laver<\/h3>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Cause possible<\/strong><\/td><td><strong>Solution de r\u00e9paration<\/strong><\/td><\/tr><tr><td>Obstruction du tuyau d\u2019\u00e9vacuation des eaux us\u00e9es\u00a0\u00a0<\/td><td>D\u00e9boucher le tuyau avec un furet ou un m\u00e9lange vinaigre\/bicarbonate de soude<\/td><\/tr><tr><td>Joint d\u2019\u00e9tanch\u00e9it\u00e9 du tuyau externe d\u00e9fectueux\u00a0\u00a0\u00a0<\/td><td>Remplacer le joint<\/td><\/tr><tr><td>Tuyau de vidange endommag\u00e9<\/td><td>Remplacer le tuyau\u00a0<\/td><\/tr><tr><td>Raccordement au r\u00e9seau d\u2019eau desserr\u00e9 (machine \u00e0 laver fuit au d\u00e9marrage)\u00a0<\/td><td>Resserrer le robinet d\u2019arriv\u00e9e d\u2019eau avec une pince<\/td><\/tr><tr><td>Roulement d\u00e9t\u00e9rior\u00e9\u00a0\u00a0<\/td><td>V\u00e9rifier l\u2019\u00e9tat du roulement en faisant tourner le tambour, un remplacement sera probablement n\u00e9cessaire<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Avant de la machine \u00e0 laver<\/h3>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Cause possible<\/strong><\/td><td><strong>Solution de r\u00e9paration<\/strong><\/td><\/tr><tr><td>Bac \u00e0 lessive entartr\u00e9<\/td><td>Nettoyer le bac \u00e0 d\u00e9tergents avec de l\u2019eau chaude et du vinaigre blanc\u00a0<\/td><\/tr><tr><td>D\u00e9faut du joint d\u2019\u00e9tanch\u00e9it\u00e9 de la porte\u00a0<\/td><td>Remplacer le joint de hublot <\/td><\/tr><tr><td>Pressostat d\u00e9fectueux<\/td><td>Changer le pressostat<\/td><\/tr><tr><td>Chambre de compression obstru\u00e9e<\/td><td>Nettoyer la chambre<\/td><\/tr><tr><td>Sol instable\u00a0<\/td><td>Positionner la machine \u00e0 laver votre lave-linge sur un endroit stable<\/td><\/tr><tr><td>Exc\u00e8s de lessive<\/td><td>Ne pas d\u00e9passer les doses de produit indiqu\u00e9es\u00a0<\/td><\/tr><tr><td>Surcharge de v\u00eatement\u00a0\u00a0<\/td><td>Respecter la charge de v\u00eatement autoris\u00e9e<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Bas de la machine \u00e0 laver<\/h3>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Cause possible<\/strong><\/td><td><strong>Solution de r\u00e9paration<\/strong><\/td><\/tr><tr><td>Tambour perc\u00e9<\/td><td>Changer le tambour<\/td><\/tr><tr><td>Pompe de vidange ou siphon bouch\u00e9<\/td><td>Nettoyer le filtre \u00e0 pompe et l\u2019\u00e9vacuation pour la d\u00e9boucher<\/td><\/tr><tr><td>Joint ab\u00eem\u00e9<\/td><td>En cas de perte d\u2019\u00e9tanch\u00e9it\u00e9, remplacer le joint<\/td><\/tr><tr><td>Durite fissur\u00e9e ou perc\u00e9e<\/td><td>Changer la durite d\u00e9fectueuse<\/td><\/tr><tr><td>R\u00e9sistance endommag\u00e9e<\/td><td>Remplacer la r\u00e9sistance<\/td><\/tr><tr><td>Carte \u00e9lectronique d\u00e9faillante<\/td><td>Pr\u00e9voir un changement de carte \u00e9lectronique<\/td><\/tr><tr><td>Tuyau de vidange d\u00e9fectueux<\/td><td>Changer le tuyau de vidange <\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n    <div class=\"bon-a-savoir\">\r\n        <div class=\"bon-a-savoir-wrapper\">\r\n            <div class=\"bon-a-savoir-header\">\r\n                <div class=\"bon-a-savoir-header-icon\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\">\r\n                        <path d=\"M0 16C0 7.16344 7.16344 0 16 0C24.8366 0 32 7.16344 32 16V32H16C7.16344 32 0 24.8366 0 16Z\" fill=\"#1591F0\" \/>\r\n                        <path d=\"M13.3359 15.3966C13.3359 14.9167 13.5266 14.4564 13.8659 14.1171C14.2053 13.7777 14.6655 13.5871 15.1455 13.5871H17.5582C18.0381 13.5871 18.4983 13.7777 18.8377 14.1171C19.177 14.4564 19.3677 14.9167 19.3677 15.3966V22.0315H19.9709C20.4508 22.0315 20.911 22.2222 21.2504 22.5615C21.5897 22.9009 21.7804 23.3611 21.7804 23.8411C21.7804 24.321 21.5897 24.7812 21.2504 25.1206C20.911 25.4599 20.4508 25.6506 19.9709 25.6506H15.1455C14.6655 25.6506 14.2053 25.4599 13.8659 25.1206C13.5266 24.7812 13.3359 24.321 13.3359 23.8411C13.3359 23.3611 13.5266 22.9009 13.8659 22.5615C14.2053 22.2222 14.6655 22.0315 15.1455 22.0315H15.7486V17.2061H15.1455C14.6655 17.2061 14.2053 17.0155 13.8659 16.6761C13.5266 16.3368 13.3359 15.8765 13.3359 15.3966ZM16.955 11.1744C16.3151 11.1744 15.7014 10.9202 15.249 10.4677C14.7965 10.0153 14.5423 9.40158 14.5423 8.7617C14.5423 8.12181 14.7965 7.50813 15.249 7.05566C15.7014 6.60319 16.3151 6.349 16.955 6.349C17.5949 6.349 18.2086 6.60319 18.661 7.05566C19.1135 7.50813 19.3677 8.12181 19.3677 8.7617C19.3677 9.40158 19.1135 10.0153 18.661 10.4677C18.2086 10.9202 17.5949 11.1744 16.955 11.1744Z\" fill=\"white\" \/>\r\n                    <\/svg>\r\n                <\/div>\r\n                <div class=\"bon-a-savoir-header-title\">Bon \u00e0 savoir<\/div>\r\n            <\/div>\r\n\r\n            <div class=\"bon-a-savoir-content\">\r\n                <p>Pour r\u00e9parer une machine \u00e0 laver qui fuit, il peut \u00eatre n\u00e9cessaire de <a href=\"https:\/\/travaux.obat.fr\/plombier\" target=\"_blank\" rel=\"noreferrer noopener\">contacter un plombier professionnel<\/a>. Si vous n\u2019\u00eates pas s\u00fbr de vous, il est en effet pr\u00e9f\u00e9rable de ne pas se lancer dans des r\u00e9parations par vous-m\u00eame.<\/p>\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\n\n\n<p class=\"wp-block-paragraph\"><em>A lire \u00e9galement : <a rel=\"noreferrer noopener\" href=\"https:\/\/travaux.obat.fr\/guides\/tarif-plombier\/\" target=\"_blank\">Quel est le tarif d\u2019un plombier? Prix d\u2019une intervention<\/a><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les bons gestes pour pr\u00e9venir les fuites futures<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le choix d\u2019un lave-linge n\u2019est pas anodin et repr\u00e9sente souvent un investissement important. Pour rentabiliser au mieux son achat et s\u2019assurer de la p\u00e9rennit\u00e9 de son appareil \u00e9lectrom\u00e9nager, il est essentiel de bien l\u2019entretenir. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 cet effet, voici quelques bons gestes faciles \u00e0 appliquer pour <strong>pr\u00e9venir les fuites de sa machine \u00e0 laver<\/strong> :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>nettoyer r\u00e9guli\u00e8rement le tiroir \u00e0 produit, le filtre de vidange, le filtre de la pompe ainsi que le tambour pour \u00e9viter l\u2019accumulation de r\u00e9sidus\u2009;<\/li>\n\n\n\n<li>veiller \u00e0 ne pas surcharger la machine\u2009;<\/li>\n\n\n\n<li>v\u00e9rifier les poches de vos v\u00eatements avant de les mettre \u00e0 laver\u2009;<\/li>\n\n\n\n<li>s\u2019assurer que le tuyau d\u2019\u00e9vacuation des eaux us\u00e9es ne pr\u00e9sente pas de d\u00e9p\u00f4t ni de bouchon\u2009;<\/li>\n\n\n\n<li>programmer ponctuellement un cycle de lavage \u00e0 vide avec du vinaigre blanc et du bicarbonate de soude pour \u00e9liminer le calcaire et dissoudre les salet\u00e9s et autres r\u00e9sidus\u2009;<\/li>\n\n\n\n<li>respecter les doses de lessive ou d\u2019adoucissant pour \u00e9viter d\u2019encrasser votre lave-linge.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A lire \u00e9galement : <a href=\"https:\/\/travaux.obat.fr\/guides\/degat-des-eaux\/\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9g\u00e2t des eaux : comment r\u00e9agir et le d\u00e9clarer ?<\/a><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pour r\u00e9sumer&nbsp;&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Selon les pannes, certains gestes peuvent \u00eatre faciles \u00e0 adopter pour<strong> r\u00e9parer une machine \u00e0 laver qui fuit<\/strong>. Pour gagner du temps et \u00e9viter de mauvaises manipulations, il reste n\u00e9anmoins recommand\u00e9 de s\u2019adresser \u00e0 un professionnel comp\u00e9tent. <strong>Un plombier qualifi\u00e9<\/strong> sait d\u00e9tecter la panne et la r\u00e9soudre sans difficult\u00e9. Pour \u00eatre s\u00fbr de ne pas se tromper, voici quelques conseils utiles pour <a href=\"https:\/\/travaux.obat.fr\/guides\/trouver-un-artisan\/\">trouver un artisan qualifi\u00e9<\/a> pr\u00e8s de chez vous qui vous assure une prestation rapide et de qualit\u00e9.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;358&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Notez cet article&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;16&quot;,&quot;title&quot;:&quot;Que faire en cas de fuite de machine \u00e0 laver ?&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12.8px;\">\n            <span class=\"kksr-muted\">Notez cet article<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Votre machine \u00e0 laver fuit\u2009? Constater que votre salle de bain ou votre buanderie devient une pataugeoire n\u2019est pas vraiment bon signe. Si votre lave-linge baigne dans une flaque d\u2019eau, il y a peu de doute possible\u2009! Il s\u2019agit tr\u00e8s certainement d\u2019une fuite. Pour \u00e9viter d\u2019endommager votre \u00e9quipement, le sol et les meubles autour, mieux [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretien-maison"],"acf":{"adam_custom_cta_bloc":{"adam_cb_text":"Une offre accessible \u00e0 tous et sans engagement","adam_cb_cta_text":"D\u00e9couvrir nos tarifs","adam_cb_cta_link":"https:\/\/www.obat.fr\/","adam_cb_cta_link_target":false,"adam_cb_image":""},"adam_posts_cta_bloc":{"adam_cb_image":"","adam_cb_titre":"Trouvez des chantiers en sous traitance pr\u00e8s de chez vous.","adam_cb_description":"","adam_cb_cta":""},"hide_the_universal_cta":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Machine \u00e0 laver qui fuit : comment r\u00e9agir\u2009? Les bons gestes<\/title>\n<meta name=\"description\" content=\"Votre machine \u00e0 laver fuit ? Avant de c\u00e9der \u00e0 la panique, voici les diff\u00e9rences causes ET les solutions possibles pour r\u00e9soudre le probl\u00e8me.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Machine \u00e0 laver qui fuit : comment r\u00e9agir\u2009? Les bons gestes\" \/>\n<meta property=\"og:description\" content=\"Votre machine \u00e0 laver fuit ? Avant de c\u00e9der \u00e0 la panique, voici les diff\u00e9rences causes ET les solutions possibles pour r\u00e9soudre le probl\u00e8me.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/\" \/>\n<meta property=\"og:site_name\" content=\"Trouver un artisan qualifi\u00e9 pr\u00e8s de chez vous pour vos travaux | Obat\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-20T16:05:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-29T15:10:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travaux.obat.fr\/guides\/wp-content\/uploads\/2023\/09\/machine-a-laver-fuit.png\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"L&#039;\u00e9quipe de r\u00e9daction\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"L&#039;\u00e9quipe de r\u00e9daction\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/machine-a-laver-fuit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/machine-a-laver-fuit\\\/\"},\"author\":{\"name\":\"L'\u00e9quipe de r\u00e9daction\",\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/#\\\/schema\\\/person\\\/d246e9f0a5ed8ef2b0381f565b669c9d\"},\"headline\":\"Que faire en cas de fuite de machine \u00e0 laver ?\",\"datePublished\":\"2023-09-20T16:05:54+00:00\",\"dateModified\":\"2024-10-29T15:10:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/machine-a-laver-fuit\\\/\"},\"wordCount\":1586,\"image\":{\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/machine-a-laver-fuit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/machine-a-laver-fuit.png\",\"articleSection\":[\"Entretien et d\u00e9pannage\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/machine-a-laver-fuit\\\/\",\"url\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/machine-a-laver-fuit\\\/\",\"name\":\"Machine \u00e0 laver qui fuit : comment r\u00e9agir\u2009? Les bons gestes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/machine-a-laver-fuit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/machine-a-laver-fuit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/machine-a-laver-fuit.png\",\"datePublished\":\"2023-09-20T16:05:54+00:00\",\"dateModified\":\"2024-10-29T15:10:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/#\\\/schema\\\/person\\\/d246e9f0a5ed8ef2b0381f565b669c9d\"},\"description\":\"Votre machine \u00e0 laver fuit ? Avant de c\u00e9der \u00e0 la panique, voici les diff\u00e9rences causes ET les solutions possibles pour r\u00e9soudre le probl\u00e8me.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/358#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/machine-a-laver-fuit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/machine-a-laver-fuit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/machine-a-laver-fuit.png\",\"contentUrl\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/machine-a-laver-fuit.png\",\"width\":735,\"height\":360,\"caption\":\"machine \u00e0 laver qui fuit\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/#website\",\"url\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/\",\"name\":\"Trouver un artisan qualifi\u00e9 pr\u00e8s de chez vous pour vos travaux | Obat\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/#\\\/schema\\\/person\\\/d246e9f0a5ed8ef2b0381f565b669c9d\",\"name\":\"L'\u00e9quipe de r\u00e9daction\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05f3070714afbd7d6648175aeb576e19105fca737195c92ab67116458f41cf8e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05f3070714afbd7d6648175aeb576e19105fca737195c92ab67116458f41cf8e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05f3070714afbd7d6648175aeb576e19105fca737195c92ab67116458f41cf8e?s=96&d=mm&r=g\",\"caption\":\"L'\u00e9quipe de r\u00e9daction\"},\"description\":\"Compos\u00e9e d'experts passionn\u00e9s de bricolage, de r\u00e9novation et d'am\u00e9nagement, l'\u00e9quipe de r\u00e9dacteurs Obat Travaux d\u00e9crypte pour vous les meilleures techniques et concepts du march\u00e9 de la construction.\",\"url\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/author\\\/equipe_de_redaction\\\/\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/358#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guides\",\"item\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/guides\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wp Json\",\"item\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/guides\\\/wp-json\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Wp\",\"item\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/guides\\\/wp-json\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"V2\",\"item\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/guides\\\/wp-json\\\/wp\\\/v2\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Posts\",\"item\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/guides\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/\"},{\"@type\":\"ListItem\",\"position\":7,\"name\":\"358\",\"item\":\"https:\\\/\\\/travaux.obat.fr\\\/guides\\\/guides\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/358\\\/\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Machine \u00e0 laver qui fuit : comment r\u00e9agir\u2009? Les bons gestes","description":"Votre machine \u00e0 laver fuit ? Avant de c\u00e9der \u00e0 la panique, voici les diff\u00e9rences causes ET les solutions possibles pour r\u00e9soudre le probl\u00e8me.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/","og_locale":"fr_FR","og_type":"article","og_title":"Machine \u00e0 laver qui fuit : comment r\u00e9agir\u2009? Les bons gestes","og_description":"Votre machine \u00e0 laver fuit ? Avant de c\u00e9der \u00e0 la panique, voici les diff\u00e9rences causes ET les solutions possibles pour r\u00e9soudre le probl\u00e8me.","og_url":"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/","og_site_name":"Trouver un artisan qualifi\u00e9 pr\u00e8s de chez vous pour vos travaux | Obat","article_published_time":"2023-09-20T16:05:54+00:00","article_modified_time":"2024-10-29T15:10:36+00:00","og_image":[{"width":735,"height":360,"url":"https:\/\/travaux.obat.fr\/guides\/wp-content\/uploads\/2023\/09\/machine-a-laver-fuit.png","type":"image\/png"}],"author":"L'\u00e9quipe de r\u00e9daction","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"L'\u00e9quipe de r\u00e9daction","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/#article","isPartOf":{"@id":"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/"},"author":{"name":"L'\u00e9quipe de r\u00e9daction","@id":"https:\/\/travaux.obat.fr\/guides\/#\/schema\/person\/d246e9f0a5ed8ef2b0381f565b669c9d"},"headline":"Que faire en cas de fuite de machine \u00e0 laver ?","datePublished":"2023-09-20T16:05:54+00:00","dateModified":"2024-10-29T15:10:36+00:00","mainEntityOfPage":{"@id":"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/"},"wordCount":1586,"image":{"@id":"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/#primaryimage"},"thumbnailUrl":"https:\/\/travaux.obat.fr\/guides\/wp-content\/uploads\/2023\/09\/machine-a-laver-fuit.png","articleSection":["Entretien et d\u00e9pannage"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/","url":"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/","name":"Machine \u00e0 laver qui fuit : comment r\u00e9agir\u2009? Les bons gestes","isPartOf":{"@id":"https:\/\/travaux.obat.fr\/guides\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/#primaryimage"},"image":{"@id":"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/#primaryimage"},"thumbnailUrl":"https:\/\/travaux.obat.fr\/guides\/wp-content\/uploads\/2023\/09\/machine-a-laver-fuit.png","datePublished":"2023-09-20T16:05:54+00:00","dateModified":"2024-10-29T15:10:36+00:00","author":{"@id":"https:\/\/travaux.obat.fr\/guides\/#\/schema\/person\/d246e9f0a5ed8ef2b0381f565b669c9d"},"description":"Votre machine \u00e0 laver fuit ? Avant de c\u00e9der \u00e0 la panique, voici les diff\u00e9rences causes ET les solutions possibles pour r\u00e9soudre le probl\u00e8me.","breadcrumb":{"@id":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/posts\/358#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/travaux.obat.fr\/guides\/machine-a-laver-fuit\/#primaryimage","url":"https:\/\/travaux.obat.fr\/guides\/wp-content\/uploads\/2023\/09\/machine-a-laver-fuit.png","contentUrl":"https:\/\/travaux.obat.fr\/guides\/wp-content\/uploads\/2023\/09\/machine-a-laver-fuit.png","width":735,"height":360,"caption":"machine \u00e0 laver qui fuit"},{"@type":"WebSite","@id":"https:\/\/travaux.obat.fr\/guides\/#website","url":"https:\/\/travaux.obat.fr\/guides\/","name":"Trouver un artisan qualifi\u00e9 pr\u00e8s de chez vous pour vos travaux | Obat","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travaux.obat.fr\/guides\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/travaux.obat.fr\/guides\/#\/schema\/person\/d246e9f0a5ed8ef2b0381f565b669c9d","name":"L'\u00e9quipe de r\u00e9daction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/05f3070714afbd7d6648175aeb576e19105fca737195c92ab67116458f41cf8e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05f3070714afbd7d6648175aeb576e19105fca737195c92ab67116458f41cf8e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05f3070714afbd7d6648175aeb576e19105fca737195c92ab67116458f41cf8e?s=96&d=mm&r=g","caption":"L'\u00e9quipe de r\u00e9daction"},"description":"Compos\u00e9e d'experts passionn\u00e9s de bricolage, de r\u00e9novation et d'am\u00e9nagement, l'\u00e9quipe de r\u00e9dacteurs Obat Travaux d\u00e9crypte pour vous les meilleures techniques et concepts du march\u00e9 de la construction.","url":"https:\/\/travaux.obat.fr\/guides\/author\/equipe_de_redaction\/"},{"@type":"BreadcrumbList","@id":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/posts\/358#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/travaux.obat.fr\/guides\/"},{"@type":"ListItem","position":2,"name":"Guides","item":"https:\/\/travaux.obat.fr\/guides\/guides\/"},{"@type":"ListItem","position":3,"name":"Wp Json","item":"https:\/\/travaux.obat.fr\/guides\/guides\/wp-json\/"},{"@type":"ListItem","position":4,"name":"Wp","item":"https:\/\/travaux.obat.fr\/guides\/guides\/wp-json\/wp\/"},{"@type":"ListItem","position":5,"name":"V2","item":"https:\/\/travaux.obat.fr\/guides\/guides\/wp-json\/wp\/v2\/"},{"@type":"ListItem","position":6,"name":"Posts","item":"https:\/\/travaux.obat.fr\/guides\/guides\/wp-json\/wp\/v2\/posts\/"},{"@type":"ListItem","position":7,"name":"358","item":"https:\/\/travaux.obat.fr\/guides\/guides\/wp-json\/wp\/v2\/posts\/358\/"}]}]}},"_links":{"self":[{"href":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/posts\/358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/comments?post=358"}],"version-history":[{"count":12,"href":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/posts\/358\/revisions"}],"predecessor-version":[{"id":2434,"href":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/posts\/358\/revisions\/2434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/media\/363"}],"wp:attachment":[{"href":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/media?parent=358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/categories?post=358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travaux.obat.fr\/guides\/wp-json\/wp\/v2\/tags?post=358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}